{"id":8746,"date":"2022-12-13T17:20:44","date_gmt":"2022-12-13T16:20:44","guid":{"rendered":"http:\/\/geniodelbosco.youelba.com\/chi-siamo\/"},"modified":"2025-10-15T14:52:12","modified_gmt":"2025-10-15T12:52:12","slug":"uber-uns","status":"publish","type":"page","link":"https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/","title":{"rendered":"Uber uns"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8746\" class=\"elementor elementor-8746 elementor-7863\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c8606f elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"7c8606f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-891fa75\" data-id=\"891fa75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-089f514 elementor-widget elementor-widget-image\" data-id=\"089f514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.appartamentisoladelba.it\/wp-content\/uploads\/2025\/10\/PAGINA-CHI-SIAMO-e1759847911122.png\" class=\"attachment-full size-full wp-image-14738\" alt=\"Loghi di viaggi del genio e di Tesi Viaggi\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9d1536 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d9d1536\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d579593 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"d579593\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c6d8e9\" data-id=\"1c6d8e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a795f84 elementor-widget elementor-widget-text-editor\" data-id=\"a795f84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<center><h2 style=\"font-size: 32px;\">Uber Uns<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c02ef26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c02ef26\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6f2a936\" data-id=\"6f2a936\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a90221c elementor-widget elementor-widget-spacer\" data-id=\"a90221c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb9873f elementor-widget elementor-widget-text-editor\" data-id=\"eb9873f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Appartamenti Isola d&#8217;Elba<\/strong> ist die Marke des Reiseveranstalters Viaggi del Genio, der sich dem Urlaub am Meer auf der Insel Elba widmet. Das Unternehmen ist seit vielen Jahren in diesem Gebiet t\u00e4tig und verf\u00fcgt \u00fcber ein erfahrenes Team von Fachleuten und Liebhabern der Insel und des toskanischen Archipels.<br \/><br \/>Seit 2026 arbeitet das Reiseb\u00fcro <a href=\"https:\/\/www.tesiviaggi.it\/de\/?utm_source=Outbound&amp;utm_medium=geniodelbosco\"><strong>Tesi Viaggi<\/strong><\/a> eng mit Viaggi del Genio bei der Verwaltung des Apartmentbereichs zusammen. Sowohl bei der Buchung als auch w\u00e4hrend deines Aufenthalts auf Elba wirst du vom Team von Tesi Viaggi betreut, das dir jederzeit zur Verf\u00fcgung steht.<\/p><h3 style=\"font-size: 18pt;\">Was wir tun und warum Sie bei uns buchen sollten<\/h3><p>Wenn Sie sich Appartamenti Isola D&#8217;Elba anvertrauen, stehen Ihnen spezialisierte Mitarbeiter zur Verf\u00fcgung, die Sie in jeder Phase Ihres Urlaubs begleiten, die besten H\u00e4user und Wohnungen, die von unserem <strong>Personal sorgf\u00e4ltig<\/strong> f\u00fcr Sie ausgew\u00e4hlt wurden, eine umfassende Betreuung und die Beratung durch das \u00f6rtliche Personal \u00fcber die besten Ausflugsziele.<\/p><p>Wir \u00fcberlassen nichts dem Zufall:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a73cf18 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a73cf18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">wir h\u00f6ren Ihnen zu, wir verstehen Ihre Bed\u00fcrfnisse<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">wir empfehlen Ihnen die f\u00fcr Sie am besten geeignete Einrichtung aus unserem Angebot<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">wir unterst\u00fctzen Sie bei der Buchung und w\u00e4hrend Ihres gesamten Aufenthalts auf Elba<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wir stellen Ihnen die wichtigsten und vielleicht verborgensten Aspekte der Insel vor, die nur denjenigen bekannt sind, die sie tagt\u00e4glich erleben<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dffeda6 elementor-widget elementor-widget-text-editor\" data-id=\"dffeda6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"line-height: 30px;\"><p><strong>Wir versprechen Ihnen, dass Sie sich bei uns wie zu Hause f\u00fchlen, nicht nur im Urlaub.<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-d13d635 elementor-widget elementor-widget-spacer\" data-id=\"d13d635\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Uber Uns Appartamenti Isola d&#8217;Elba ist die Marke des Reiseveranstalters Viaggi del Genio, der sich dem Urlaub am Meer auf der Insel Elba widmet. Das Unternehmen ist seit vielen Jahren in diesem Gebiet t\u00e4tig und verf\u00fcgt \u00fcber ein erfahrenes Team von Fachleuten und Liebhabern der Insel und des toskanischen Archipels. Seit 2026 arbeitet das Reiseb\u00fcro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14738,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template\/template-homepage.php","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-8746","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uber uns - Appartamenti Isola d&#039;Elba<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uber uns - Appartamenti Isola d&#039;Elba\" \/>\n<meta property=\"og:description\" content=\"Uber Uns Appartamenti Isola d&#8217;Elba ist die Marke des Reiseveranstalters Viaggi del Genio, der sich dem Urlaub am Meer auf der Insel Elba widmet. Das Unternehmen ist seit vielen Jahren in diesem Gebiet t\u00e4tig und verf\u00fcgt \u00fcber ein erfahrenes Team von Fachleuten und Liebhabern der Insel und des toskanischen Archipels. Seit 2026 arbeitet das Reiseb\u00fcro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/\" \/>\n<meta property=\"og:site_name\" content=\"Appartamenti Isola d&#039;Elba\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/appartamentisoladelba\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T12:52:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.appartamentisoladelba.it\/wp-content\/uploads\/2025\/10\/PAGINA-CHI-SIAMO-e1759847911122.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uber uns - Appartamenti Isola d&#039;Elba","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/","og_locale":"de_DE","og_type":"article","og_title":"Uber uns - Appartamenti Isola d&#039;Elba","og_description":"Uber Uns Appartamenti Isola d&#8217;Elba ist die Marke des Reiseveranstalters Viaggi del Genio, der sich dem Urlaub am Meer auf der Insel Elba widmet. Das Unternehmen ist seit vielen Jahren in diesem Gebiet t\u00e4tig und verf\u00fcgt \u00fcber ein erfahrenes Team von Fachleuten und Liebhabern der Insel und des toskanischen Archipels. Seit 2026 arbeitet das Reiseb\u00fcro [&hellip;]","og_url":"https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/","og_site_name":"Appartamenti Isola d&#039;Elba","article_publisher":"https:\/\/www.facebook.com\/appartamentisoladelba\/","article_modified_time":"2025-10-15T12:52:12+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.appartamentisoladelba.it\/wp-content\/uploads\/2025\/10\/PAGINA-CHI-SIAMO-e1759847911122.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/","url":"https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/","name":"Uber uns - Appartamenti Isola d&#039;Elba","isPartOf":{"@id":"https:\/\/www.appartamentisoladelba.it\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/#primaryimage"},"image":{"@id":"https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/#primaryimage"},"thumbnailUrl":"https:\/\/www.appartamentisoladelba.it\/wp-content\/uploads\/2025\/10\/PAGINA-CHI-SIAMO-e1759847911122.png","datePublished":"2022-12-13T16:20:44+00:00","dateModified":"2025-10-15T12:52:12+00:00","breadcrumb":{"@id":"https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/#primaryimage","url":"https:\/\/www.appartamentisoladelba.it\/wp-content\/uploads\/2025\/10\/PAGINA-CHI-SIAMO-e1759847911122.png","contentUrl":"https:\/\/www.appartamentisoladelba.it\/wp-content\/uploads\/2025\/10\/PAGINA-CHI-SIAMO-e1759847911122.png","width":1920,"height":1080,"caption":"Loghi di viaggi del genio e di Tesi Viaggi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.appartamentisoladelba.it\/de\/uber-uns\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.appartamentisoladelba.it\/de\/"},{"@type":"ListItem","position":2,"name":"Uber uns"}]},{"@type":"WebSite","@id":"https:\/\/www.appartamentisoladelba.it\/de\/#website","url":"https:\/\/www.appartamentisoladelba.it\/de\/","name":"Appartamenti Isola d'Elba","description":"Wohnungen zur Miete auf der Insel Elba f\u00fcr den Sommer","publisher":{"@id":"https:\/\/www.appartamentisoladelba.it\/de\/#organization"},"alternateName":"Appartamenti Elba","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.appartamentisoladelba.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.appartamentisoladelba.it\/de\/#organization","name":"Appartamenti Isola d'Elba","alternateName":"Appartamenti Elba","url":"https:\/\/www.appartamentisoladelba.it\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.appartamentisoladelba.it\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.appartamentisoladelba.it\/wp-content\/uploads\/2026\/01\/logo_appartamenti_2000px_testo_superdef.jpg","contentUrl":"https:\/\/www.appartamentisoladelba.it\/wp-content\/uploads\/2026\/01\/logo_appartamenti_2000px_testo_superdef.jpg","width":2000,"height":2000,"caption":"Appartamenti Isola d'Elba"},"image":{"@id":"https:\/\/www.appartamentisoladelba.it\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/appartamentisoladelba\/","https:\/\/www.instagram.com\/appartamentisoladelba\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.appartamentisoladelba.it\/de\/wp-json\/wp\/v2\/pages\/8746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.appartamentisoladelba.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.appartamentisoladelba.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.appartamentisoladelba.it\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.appartamentisoladelba.it\/de\/wp-json\/wp\/v2\/comments?post=8746"}],"version-history":[{"count":3,"href":"https:\/\/www.appartamentisoladelba.it\/de\/wp-json\/wp\/v2\/pages\/8746\/revisions"}],"predecessor-version":[{"id":14882,"href":"https:\/\/www.appartamentisoladelba.it\/de\/wp-json\/wp\/v2\/pages\/8746\/revisions\/14882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.appartamentisoladelba.it\/de\/wp-json\/wp\/v2\/media\/14738"}],"wp:attachment":[{"href":"https:\/\/www.appartamentisoladelba.it\/de\/wp-json\/wp\/v2\/media?parent=8746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}